{"id":6,"count":3,"description":"Suitable for everyone, including children and seniors. No special skills are required, and activities take place on easy terrain.","link":"https:\/\/naturahimalayatours.com\/es\/trip-difficulty\/easy\/","name":"Easy","slug":"easy","taxonomy":"difficulty","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/naturahimalayatours.com\/es\/wp-json\/wp\/v2\/difficulty\/6","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/naturahimalayatours.com\/es\/wp-json\/wp\/v2\/difficulty"}],"about":[{"href":"https:\/\/naturahimalayatours.com\/es\/wp-json\/wp\/v2\/taxonomies\/difficulty"}],"wp:post_type":[{"href":"https:\/\/naturahimalayatours.com\/es\/wp-json\/wp\/v2\/trip?difficulty=6"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}